{"id":10469,"date":"2020-09-15T12:56:54","date_gmt":"2020-09-15T12:56:54","guid":{"rendered":"https:\/\/vantage-dc.com\/additional_resources\/how-data-center-providers-are-building-green-every-step-of-the-way\/"},"modified":"2022-03-18T14:50:17","modified_gmt":"2022-03-18T18:50:17","slug":"how-data-center-providers-are-building-green-every-step-of-the-way","status":"publish","type":"additional_resources","link":"https:\/\/vantage-dc.com\/fr\/additional_resources\/how-data-center-providers-are-building-green-every-step-of-the-way\/","title":{"rendered":"Comment les fournisseurs de datacenter construisent de mani\u00e8re \u00e9cologique \u00e0 chaque \u00e9tape du processus"},"content":{"rendered":"<p>Les datacenters n\u00e9cessitent de l&rsquo;\u00e9nergie. Voici comment les entreprises technologiques et les fournisseurs de datacenter d&rsquo;aujourd&rsquo;hui passent au vert et r\u00e9duisent leur impact sur l&rsquo;environnement.<\/p>\n","protected":false},"featured_media":10470,"template":"","class_list":["post-10469","additional_resources","type-additional_resources","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/vantage-dc.com\/fr\/wp-json\/wp\/v2\/additional_resources\/10469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vantage-dc.com\/fr\/wp-json\/wp\/v2\/additional_resources"}],"about":[{"href":"https:\/\/vantage-dc.com\/fr\/wp-json\/wp\/v2\/types\/additional_resources"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vantage-dc.com\/fr\/wp-json\/wp\/v2\/media\/10470"}],"wp:attachment":[{"href":"https:\/\/vantage-dc.com\/fr\/wp-json\/wp\/v2\/media?parent=10469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}